{"id":21667,"date":"2022-08-15T11:11:04","date_gmt":"2022-08-15T15:11:04","guid":{"rendered":"https:\/\/elearning.wfh.org\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/"},"modified":"2022-09-08T10:47:12","modified_gmt":"2022-09-08T14:47:12","slug":"apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021","status":"publish","type":"resource","link":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/","title":{"rendered":"Aper\u00e7u de l&rsquo;acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021"},"content":{"rendered":"<p class=\"clamp_p\">Comment la pand\u00e9mie affecte-t-elle les syst\u00e8mes de sant\u00e9 du monde entier ? En quoi consistera \u00ab la nouvelle normalit\u00e9 \u00bb ? Dans cette session d\u2019ouverture du Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins, Cesar Garrido (pr\u00e9sident de la FMH) et le Dr Glenn Pierce (vice-pr\u00e9sident de la FMH en charge des affaires m\u00e9dicales) parlent des effets de la pand\u00e9mie sur la vision de la FMH du Traitement pour tous, et soulignent l\u2019\u00e9tat actuel de l\u2019acc\u00e8s au traitement et aux soins. L\u2019invit\u00e9e principale, le Dr Mari\u00e2ngela Sim\u00e3o (OMS), s\u2019exprime sur l\u2019impact des priorit\u00e9s de la Couverture sanitaire universelle et des Objectifs de d\u00e9veloppement durable sur l\u2019acc\u00e8s aux soins pour les personnes atteintes d\u2019un trouble de la coagulation. Rejoignez-nous pour d\u00e9couvrir quels doivent \u00eatre les r\u00f4les respectifs des organisations de patient\u00b7es, des professionnel\u00b7les de sant\u00e9 et des gouvernements dans l\u2019am\u00e9lioration de l\u2019acc\u00e8s aux soins.<\/p>\n<p class=\"clamp_p\" style=\"margin-bottom: 2em;\">Ce webinaire de la FMH a initialement \u00e9t\u00e9 pr\u00e9sent\u00e9 en anglais.<\/p>\n<div class=\"alert alert-danger\" style=\"color: #333333!important; border-color: #fedede; background-color: #fdeaea; padding: 1em 1em 1em 4em; position: relative; margin-top: 1em;\">\n<div style=\"bottom: 0; left: 0; position: absolute; top: 0; width: 4em; color: #ff7877;\">\n<p class=\"fa fa-info-circle\" style=\"left: 50%; top: 50%; position: absolute; transform: translate(-50%, -50%); font-size: 1.7em;\">\n<\/div>\n<p class=\"\">La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie ne pratique pas la m\u00e9decine et ne recommande en aucun cas de traitement pr\u00e9cis \u00e0 qui que ce soit. Pour un diagnostic ou une consultation sur un probl\u00e8me m\u00e9dical sp\u00e9cifique, la FMH vous recommande de contacter votre m\u00e9decin ou le centre de traitement local. Avant d\u2019administrer tout produit, la FMH recommande aux patients de v\u00e9rifier les doses avec un m\u00e9decin ou le personnel du centre de traitement, et de consulter les instructions \u00e9crites fournies par le laboratoire pharmaceutique.<\/p>\n<p class=\"\">La FMH ne fait la promotion d\u2019aucun produit pharmaceutique particulier et toute mention d\u2019une marque commerciale dans cette pr\u00e9sentation est strictement \u00e0 des fins \u00e9ducatives.<\/p>\n<\/div>\n","protected":false},"featured_media":21656,"template":"","format":[3951],"old-keyword":[],"topic":[3995],"serie":[4243],"class_list":["post-21667","resource","type-resource","status-publish","has-post-thumbnail","hentry","topic-plaidoyer","format-videos-fr","serie-congres-et-evenements"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aper\u00e7u de l&#039;acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aper\u00e7u de l&#039;acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform\" \/>\n<meta property=\"og:description\" content=\"Comment la pand\u00e9mie affecte-t-elle les syst\u00e8mes de sant\u00e9 du monde entier ? En quoi consistera \u00ab la nouvelle normalit\u00e9 \u00bb ? Dans cette session d\u2019ouverture du Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins, Cesar Garrido (pr\u00e9sident de la FMH) et le Dr Glenn Pierce (vice-pr\u00e9sident de la FMH en charge des affaires m\u00e9dicales) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"eLearning Platform\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T14:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/08\/GPAS2021-current-landscape-770x410-FR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/\",\"name\":\"Aper\u00e7u de l'acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GPAS2021-current-landscape-770x410-FR.png\",\"datePublished\":\"2022-08-15T15:11:04+00:00\",\"dateModified\":\"2022-09-08T14:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GPAS2021-current-landscape-770x410-FR.png\",\"contentUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GPAS2021-current-landscape-770x410-FR.png\",\"width\":770,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aper\u00e7u de l&#8217;acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/\",\"name\":\"eLearning Platform\",\"description\":\"World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#organization\",\"name\":\"eLearning Platform\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WFH-eLearning-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WFH-eLearning-Logo-RGB.png\",\"width\":1460,\"height\":418,\"caption\":\"eLearning Platform\"},\"image\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aper\u00e7u de l'acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Aper\u00e7u de l'acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform","og_description":"Comment la pand\u00e9mie affecte-t-elle les syst\u00e8mes de sant\u00e9 du monde entier ? En quoi consistera \u00ab la nouvelle normalit\u00e9 \u00bb ? Dans cette session d\u2019ouverture du Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins, Cesar Garrido (pr\u00e9sident de la FMH) et le Dr Glenn Pierce (vice-pr\u00e9sident de la FMH en charge des affaires m\u00e9dicales) [&hellip;]","og_url":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/","og_site_name":"eLearning Platform","article_modified_time":"2022-09-08T14:47:12+00:00","og_image":[{"width":770,"height":410,"url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/08\/GPAS2021-current-landscape-770x410-FR.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/","url":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/","name":"Aper\u00e7u de l'acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021 - eLearning Platform","isPartOf":{"@id":"https:\/\/elearning.wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/#primaryimage"},"image":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/08\/GPAS2021-current-landscape-770x410-FR.png","datePublished":"2022-08-15T15:11:04+00:00","dateModified":"2022-09-08T14:47:12+00:00","breadcrumb":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/#primaryimage","url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/08\/GPAS2021-current-landscape-770x410-FR.png","contentUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/08\/GPAS2021-current-landscape-770x410-FR.png","width":770,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/apercu-de-lacces-aux-traitements-et-aux-soins-dans-le-monde-sommet-mondial-sur-les-politiques-et-lacces-aux-soins-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Resources","item":"https:\/\/elearning.wfh.org\/fr\/resource\/"},{"@type":"ListItem","position":2,"name":"Aper\u00e7u de l&#8217;acc\u00e8s aux traitements et aux soins dans le monde | Sommet mondial sur les politiques et l\u2019acc\u00e8s aux soins 2021"}]},{"@type":"WebSite","@id":"https:\/\/elearning.wfh.org\/fr\/#website","url":"https:\/\/elearning.wfh.org\/fr\/","name":"eLearning Platform","description":"World Federation of Hemophilia","publisher":{"@id":"https:\/\/elearning.wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elearning.wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/elearning.wfh.org\/fr\/#organization","name":"eLearning Platform","url":"https:\/\/elearning.wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elearning.wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/06\/WFH-eLearning-Logo-RGB.png","contentUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/06\/WFH-eLearning-Logo-RGB.png","width":1460,"height":418,"caption":"eLearning Platform"},"image":{"@id":"https:\/\/elearning.wfh.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/resource\/21667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/media\/21656"}],"wp:attachment":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=21667"}],"wp:term":[{"taxonomy":"old-keyword","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/old-keyword?post=21667"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/topic?post=21667"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/format?post=21667"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/serie?post=21667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}