{"id":1263,"date":"2021-03-30T11:00:46","date_gmt":"2021-03-30T15:00:46","guid":{"rendered":"https:\/\/elearning.wfh.org\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/"},"modified":"2022-06-06T17:09:23","modified_gmt":"2022-06-06T21:09:23","slug":"vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation","status":"publish","type":"resource","link":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/","title":{"rendered":"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation"},"content":{"rendered":"<p class=\"\">\u00c9coutez ce webinaire de 90 minutes pr\u00e9sent\u00e9 le 12 mars 2021, pour en apprendre plus sur les derni\u00e8res directives de la FMH concernant la vaccination et le traitement contre la COVID-19 chez les personnes atteintes d\u2019un trouble de la coagulation. L&rsquo;objectif de ce webinaire \u00e9tait de r\u00e9pondre aux questions concernant la COVID-19 chez les personnes atteintes d\u2019un trouble de la coagulation. C\u2019\u00e9tait l\u2019occasion pour les participants, d\u2019une part, d\u2019en apprendre davantage sur les recommandations de la FMH visant \u00e0 pr\u00e9venir et \u00e0 traiter la maladie, sur les vaccins contre la COVID-19 et, d\u2019autre part, de mieux comprendre l&rsquo;\u00e9tat actuel de l&rsquo;acc\u00e8s aux vaccins dans le monde et les risques associ\u00e9s aux vaccins chez les personnes atteintes d\u2019un trouble de la coagulation.<\/p>\n<p class=\"\">La session \u00e9tait pr\u00e9sid\u00e9e par Glenn Pierce (Vice-pr\u00e9sident, M\u00e9dical de la FMH).<\/p>\n<p class=\"\">Miguel Escobar (membre m\u00e9dical du Conseil d\u2019administration de la FMH), Cedric Hermans (membre m\u00e9dical du Conseil d\u2019administration de la FMH), Johnny Mahlangu (professeur en h\u00e9matologie), Radoslaw Kaczmarek (pr\u00e9sident du Comit\u00e9 sur la s\u00e9curit\u00e9, l&rsquo;approvisionnement et sur l&rsquo;acc\u00e8s aux m\u00e9dicaments de la FMH) et Ioana Ghiga (responsable technique, OMS) ont pr\u00e9sent\u00e9 les donn\u00e9es \u00e9pid\u00e9miologiques relatives \u00e0 la COVID-19 chez les personnes atteintes d\u2019un trouble de la coagulation, le traitement et les conseils de vaccination pour les personnes atteintes d\u2019un trouble de la coagulation, ont partag\u00e9 des perspectives sur le traitement de l&rsquo;Afrique du Sud, y compris les diff\u00e9rents variants, et ont abord\u00e9 la question de l&rsquo;accessibilit\u00e9 des vaccins au niveau mondial par le biais de l\u2019initiative COVAX de CEPI, GAVI, l&rsquo;OMS et l\u2019UNICEF.<\/p>\n<p class=\"\">Ce webinaire de la FMH a initialement \u00e9t\u00e9 pr\u00e9sent\u00e9 en anglais.<\/p>\n<p class=\"\">Pour t\u00e9l\u00e9charger un pdf des diapositives du webinaire en anglais, cliquez sur l&rsquo;ic\u00f4ne ci-dessous.<\/p>\n<p class=\"\"><a href=\"https:\/\/www1.wfh.org\/publications\/files\/pdf-1882.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"wp-image-2959 size-full aligncenter\" src=\"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2020\/04\/slides_icon-230x300-1.png\" alt=\"pdf_icon\" width=\"98\" height=\"128\" \/><\/a><\/p>\n<div class=\"alert alert-danger\" style=\"color: #333333!important; border-color: #fedede; background-color: #fdeaea; padding: 1em 1em 1em 4em; position: relative;\">\n<div style=\"bottom: 0; left: 0; position: absolute; top: 0; width: 4em; color: #ff7877;\">\n<p class=\"fa fa-info-circle\" style=\"left: 50%; top: 50%; position: absolute; transform: translate(-50%, -50%); font-size: 1.7em;\">\n<\/div>\n<p class=\"\">La F\u00e9d\u00e9ration mondiale de l\u2019h\u00e9mophilie ne pratique pas la m\u00e9decine et ne recommande en aucun cas de traitement pr\u00e9cis \u00e0 qui que ce soit. Pour un diagnostic ou une consultation sur un probl\u00e8me m\u00e9dical sp\u00e9cifique, la FMH vous recommande de contacter votre m\u00e9decin ou le centre de traitement local. Avant d&rsquo;administrer tout produit, la FMH recommande aux patients de v\u00e9rifier les doses avec un m\u00e9decin ou le personnel du centre de traitement, et de consulter les instructions \u00e9crites fournies par le laboratoire pharmaceutique.<\/p>\n<p class=\"\">La FMH ne fait la promotion d&rsquo;aucun produit pharmaceutique particulier et toute mention d&rsquo;une marque commerciale dans cette pr\u00e9sentation est strictement \u00e0 des fins \u00e9ducatives.<\/p>\n<\/div>\n","protected":false},"featured_media":2474,"template":"","format":[3951],"old-keyword":[],"topic":[],"serie":[],"class_list":["post-1263","resource","type-resource","status-publish","has-post-thumbnail","hentry","format-videos-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform\" \/>\n<meta property=\"og:description\" content=\"\u00c9coutez ce webinaire de 90 minutes pr\u00e9sent\u00e9 le 12 mars 2021, pour en apprendre plus sur les derni\u00e8res directives de la FMH concernant la vaccination et le traitement contre la COVID-19 chez les personnes atteintes d\u2019un trouble de la coagulation. L&rsquo;objectif de ce webinaire \u00e9tait de r\u00e9pondre aux questions concernant la COVID-19 chez les personnes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/\" \/>\n<meta property=\"og:site_name\" content=\"eLearning Platform\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-06T21:09:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2021\/03\/WFH-Webinar-770x410-March12-FR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/\",\"name\":\"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WFH-Webinar-770x410-March12-FR.png\",\"datePublished\":\"2021-03-30T15:00:46+00:00\",\"dateModified\":\"2022-06-06T21:09:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WFH-Webinar-770x410-March12-FR.png\",\"contentUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/WFH-Webinar-770x410-March12-FR.png\",\"width\":770,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/resource\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/\",\"name\":\"eLearning Platform\",\"description\":\"World Federation of Hemophilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#organization\",\"name\":\"eLearning Platform\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WFH-eLearning-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/elearning.wfh.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WFH-eLearning-Logo-RGB.png\",\"width\":1460,\"height\":418,\"caption\":\"eLearning Platform\"},\"image\":{\"@id\":\"https:\\\/\\\/elearning.wfh.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/","og_locale":"fr_FR","og_type":"article","og_title":"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform","og_description":"\u00c9coutez ce webinaire de 90 minutes pr\u00e9sent\u00e9 le 12 mars 2021, pour en apprendre plus sur les derni\u00e8res directives de la FMH concernant la vaccination et le traitement contre la COVID-19 chez les personnes atteintes d\u2019un trouble de la coagulation. L&rsquo;objectif de ce webinaire \u00e9tait de r\u00e9pondre aux questions concernant la COVID-19 chez les personnes [&hellip;]","og_url":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/","og_site_name":"eLearning Platform","article_modified_time":"2022-06-06T21:09:23+00:00","og_image":[{"width":770,"height":410,"url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2021\/03\/WFH-Webinar-770x410-March12-FR.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/","url":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/","name":"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation - eLearning Platform","isPartOf":{"@id":"https:\/\/elearning.wfh.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/#primaryimage"},"image":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/#primaryimage"},"thumbnailUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2021\/03\/WFH-Webinar-770x410-March12-FR.png","datePublished":"2021-03-30T15:00:46+00:00","dateModified":"2022-06-06T21:09:23+00:00","breadcrumb":{"@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/#primaryimage","url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2021\/03\/WFH-Webinar-770x410-March12-FR.png","contentUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2021\/03\/WFH-Webinar-770x410-March12-FR.png","width":770,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/elearning.wfh.org\/fr\/resource\/vaccination-et-traitement-contre-la-covid-19-pour-les-personnes-atteintes-dun-trouble-de-la-coagulation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Resources","item":"https:\/\/elearning.wfh.org\/fr\/resource\/"},{"@type":"ListItem","position":2,"name":"Vaccination et traitement contre la COVID 19 pour les personnes atteintes d\u2019un trouble de la coagulation"}]},{"@type":"WebSite","@id":"https:\/\/elearning.wfh.org\/fr\/#website","url":"https:\/\/elearning.wfh.org\/fr\/","name":"eLearning Platform","description":"World Federation of Hemophilia","publisher":{"@id":"https:\/\/elearning.wfh.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elearning.wfh.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/elearning.wfh.org\/fr\/#organization","name":"eLearning Platform","url":"https:\/\/elearning.wfh.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elearning.wfh.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/06\/WFH-eLearning-Logo-RGB.png","contentUrl":"https:\/\/elearning.wfh.org\/wp-content\/uploads\/2022\/06\/WFH-eLearning-Logo-RGB.png","width":1460,"height":418,"caption":"eLearning Platform"},"image":{"@id":"https:\/\/elearning.wfh.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/resource\/1263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/media\/2474"}],"wp:attachment":[{"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/media?parent=1263"}],"wp:term":[{"taxonomy":"old-keyword","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/old-keyword?post=1263"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/topic?post=1263"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/format?post=1263"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/elearning.wfh.org\/fr\/wp-json\/wp\/v2\/serie?post=1263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}